{"id":29,"count":22,"description":"","link":"http:\/\/lf-tools.com\/zh\/product-category\/cnc-bar\/","name":"CNC Bar","slug":"cnc-bar","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/lf-tools.com\/zh\/wp-json\/wp\/v2\/product_cat\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lf-tools.com\/zh\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"http:\/\/lf-tools.com\/zh\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"http:\/\/lf-tools.com\/zh\/wp-json\/wp\/v2\/product?product_cat=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}